{"id":44,"date":"2019-07-31T19:50:21","date_gmt":"2019-07-31T17:50:21","guid":{"rendered":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/?page_id=44"},"modified":"2019-12-10T12:22:59","modified_gmt":"2019-12-10T11:22:59","slug":"kultur-und-konflikt","status":"publish","type":"page","link":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/kultur-und-konflikt\/","title":{"rendered":"Kultur und Konflikt"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":4236,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kultur und Konflikt -<\/title>\n<meta name=\"description\" content=\"Die Tradition des britisch-protestantischen Unionismus in Belfast steht vor hehren Herausforderungen. Der Wandel ihrer Stadt ist Chance und zugleich Gefahr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/kultur-und-konflikt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kultur und Konflikt - Unionismus in Belfast\" \/>\n<meta property=\"og:description\" content=\"Die Tradition des britisch-protestantischen Unionismus in Belfast steht vor hehren Herausforderungen. Der Wandel ihrer Stadt ist Chance und zugleich Gefahr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/kultur-und-konflikt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-10T11:22:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kultur und Konflikt - Unionismus in Belfast\" \/>\n<meta name=\"twitter:description\" content=\"Die Tradition des britisch-protestantischen Unionismus in Belfast steht vor hehren Herausforderungen. Der Wandel ihrer Stadt ist Chance und zugleich Gefahr.\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\">\n\t<meta name=\"twitter:data1\" content=\"28\u00a0Minuten\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/#website\",\"url\":\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/kultur-und-konflikt\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/files\/2019\/07\/DSCN3791-2-1.jpg\",\"width\":5152,\"height\":3864},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/kultur-und-konflikt\/#webpage\",\"url\":\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/kultur-und-konflikt\/\",\"name\":\"Kultur und Konflikt -\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/kultur-und-konflikt\/#primaryimage\"},\"datePublished\":\"2019-07-31T17:50:21+00:00\",\"dateModified\":\"2019-12-10T11:22:59+00:00\",\"description\":\"Die Tradition des britisch-protestantischen Unionismus in Belfast steht vor hehren Herausforderungen. Der Wandel ihrer Stadt ist Chance und zugleich Gefahr.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/kultur-und-konflikt\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/wp-json\/wp\/v2\/pages\/44"}],"collection":[{"href":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/wp-json\/wp\/v2\/users\/4236"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":9,"href":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/wp-json\/wp\/v2\/pages\/44\/revisions"}],"predecessor-version":[{"id":182,"href":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/wp-json\/wp\/v2\/pages\/44\/revisions\/182"}],"wp:attachment":[{"href":"https:\/\/blogs.urz.uni-halle.de\/belfast2017\/wp-json\/wp\/v2\/media?parent=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}