{"id":475,"date":"2017-05-02T12:33:21","date_gmt":"2017-05-02T10:33:21","guid":{"rendered":"https:\/\/blogs.urz.uni-halle.de\/demografie\/?p=475"},"modified":"2017-05-02T13:42:21","modified_gmt":"2017-05-02T11:42:21","slug":"475","status":"publish","type":"post","link":"https:\/\/blogs.urz.uni-halle.de\/demografie\/2017\/05\/475\/","title":{"rendered":""},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-6\" src=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/files\/2017\/04\/Demopfad1-Kopie-300x266.jpg\" alt=\"\" width=\"300\" height=\"266\" srcset=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/files\/2017\/04\/Demopfad1-Kopie-300x266.jpg 300w, https:\/\/blogs.urz.uni-halle.de\/demografie\/files\/2017\/04\/Demopfad1-Kopie.jpg 369w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p class=\"hText\" style=\"text-align: justify\">Willkommen auf dem Demopfad. Hier lernen Sie die Methoden der <a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/2017\/04\/316\/\">historischen Demographie<\/a> kennen. Dargestellt wird hier der Umgang mit den grundlegenden Methoden zur Berechnung von <a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/kategorie\/demopfad\/bevoelkerungsbewgung\/\">Bev\u00f6lkerungsbewegungen<\/a>, der <a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/kategorie\/demopfad\/fertilitaet\/\">Fertilit\u00e4t<\/a> und der <a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/kategorie\/demopfad\/mortalitaet\/\">Mortalit\u00e4t<\/a>. Aber auch die Bedeutungen der wichtigsten Begriffe werden hier erkl\u00e4rt. Diese Begriffe sind z.B. <a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/2017\/04\/417\/\">Kohorten und Perioden<\/a>. Hier werden <a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/2017\/04\/393\/\">Buchf\u00fchrungsgleichungen<\/a> einer Population aufgestellt. Hier werden<a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/2017\/05\/444\/\"> Nettoreproduktionsraten<\/a> und <a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/2017\/04\/403\/\">Lebenserwartungen<\/a> berechnet. Zu jedem Themenpunkt finden Sie eine ausf\u00fchrliche Erkl\u00e4rung in Worten und <a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/2017\/04\/391\/\">mathematischer Notation<\/a> mit einem jeweils ausf\u00fchrlichen Beispiel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Willkommen auf dem Demopfad. Hier lernen Sie die Methoden der historischen Demographie kennen. Dargestellt wird hier der Umgang mit den grundlegenden Methoden zur Berechnung von Bev\u00f6lkerungsbewegungen, der Fertilit\u00e4t und der Mortalit\u00e4t. Aber auch die Bedeutungen der wichtigsten Begriffe werden hier &hellip; <a href=\"https:\/\/blogs.urz.uni-halle.de\/demografie\/2017\/05\/475\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3010,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[7],"tags":[40,46,194,42,23,44,48,49,39,38,43,47,45],"_links":{"self":[{"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/posts\/475"}],"collection":[{"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/users\/3010"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/comments?post=475"}],"version-history":[{"count":4,"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/posts\/475\/revisions"}],"predecessor-version":[{"id":484,"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/posts\/475\/revisions\/484"}],"wp:attachment":[{"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/media?parent=475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/categories?post=475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/demografie\/wp-json\/wp\/v2\/tags?post=475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}