{"id":1,"count":3,"description":"","link":"https:\/\/blogs.urz.uni-halle.de\/howtopuls\/kategorie\/allgemein\/","name":"Allgemein","slug":"allgemein","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.urz.uni-halle.de\/howtopuls\/wp-json\/wp\/v2\/categories\/1"}],"collection":[{"href":"https:\/\/blogs.urz.uni-halle.de\/howtopuls\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.urz.uni-halle.de\/howtopuls\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.urz.uni-halle.de\/howtopuls\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}