{"id":10187,"count":1,"description":"","link":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/tag\/koerber-stiftung\/","name":"K\u00f6rber-Stiftung","slug":"koerber-stiftung","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/tags\/10187"}],"collection":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/posts?tags=10187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}