{"id":10642,"count":2,"description":"","link":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/tag\/wimi\/","name":"WiMi","slug":"wimi","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/tags\/10642"}],"collection":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/posts?tags=10642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}