{"id":275,"count":1,"description":"","link":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/tag\/blair\/","name":"Blair","slug":"blair","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/tags\/275"}],"collection":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.urz.uni-halle.de\/politikwissenschaft\/wp-json\/wp\/v2\/posts?tags=275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}