{"id":457,"date":"2021-02-16T16:01:42","date_gmt":"2021-02-16T15:01:42","guid":{"rendered":"https:\/\/blogs.urz.uni-halle.de\/twain\/?page_id=457"},"modified":"2021-02-16T16:01:42","modified_gmt":"2021-02-16T15:01:42","slug":"final-projects","status":"publish","type":"page","link":"https:\/\/blogs.urz.uni-halle.de\/twain\/final-projects\/","title":{"rendered":"Final Projects"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4358,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.urz.uni-halle.de\/twain\/wp-json\/wp\/v2\/pages\/457"}],"collection":[{"href":"https:\/\/blogs.urz.uni-halle.de\/twain\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.urz.uni-halle.de\/twain\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/twain\/wp-json\/wp\/v2\/users\/4358"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/twain\/wp-json\/wp\/v2\/comments?post=457"}],"version-history":[{"count":1,"href":"https:\/\/blogs.urz.uni-halle.de\/twain\/wp-json\/wp\/v2\/pages\/457\/revisions"}],"predecessor-version":[{"id":464,"href":"https:\/\/blogs.urz.uni-halle.de\/twain\/wp-json\/wp\/v2\/pages\/457\/revisions\/464"}],"wp:attachment":[{"href":"https:\/\/blogs.urz.uni-halle.de\/twain\/wp-json\/wp\/v2\/media?parent=457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}