{"id":591,"date":"2023-09-19T11:51:23","date_gmt":"2023-09-19T09:51:23","guid":{"rendered":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/?p=591"},"modified":"2023-09-19T11:55:21","modified_gmt":"2023-09-19T09:55:21","slug":"ganz-sicher","status":"publish","type":"post","link":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/2023\/09\/ganz-sicher\/","title":{"rendered":"Ganz sicher?"},"content":{"rendered":"\n<p>Warnhinweis:<br>Das ist ein Text f\u00fcr Besserwisser*innen, Rechthaber*innen und Klugschei\u2026 Sie wissen schon.<\/p>\n\n\n\n<p>Geh\u00f6ren Sie zu einer dieser Kategorien?<br>Grunds\u00e4tzlich? Manchmal?<br>Oder fr\u00fcher mal, und jetzt nicht mehr so?<\/p>\n\n\n\n<p>Ich muss leider zugeben, dass ich ganz sch\u00f6n rechthaberisch und besserwisserisch bin. Liegt bei mir total in der Familie. Und das hat mich wahrscheinlich gerettet, denn ich sehe dieses Verhalten sehr oft und finde es wahlweise lustig oder auch ganz sch\u00f6n abschreckend, und das hilft dabei, es bei mir selbst wahrzunehmen und daran zu arbeiten.<\/p>\n\n\n\n<p>Wahrscheinlich ist also meine Familie der Grund daf\u00fcr, dass ich die Rechthaberei meistens auf ein sozialvertr\u00e4glich Ma\u00df reduzieren kann. In meinem beruflichen Umfeld begegne ich (naturgem\u00e4ss und unterst\u00fctzt durch den Halo Effect) auch sehr vielen Menschen, die immer recht haben und alles wissen. Oder das jedenfalls denken. Zum Gl\u00fcck tritt es auch da oft nur in sozialvertr\u00e4glichen Dosen auf. Trotzdem geht es in diesem Text darum, wachsam zu sein, sich immer wieder an die eigene Nase zu fassen und genug Raum f\u00fcr Zweifel zu lassen. Ausgel\u00f6st wurde das bei mir ganz konkret durch zwei Ereignisse, die innerhalb eines Zeitraums von ca. vier Wochen passiert sind.<\/p>\n\n\n\n<p>Die schildere ich jetzt und lasse Sie ein bisschen an meinem &#8222;Hochmut kommt vor dem Fall&#8220;-Gef\u00fchl teilhaben, weil solche Erlebnisse vor zu viel Besserwisserei sch\u00fctzen (k\u00f6nnen). Eigentlich klar, in der Wissenschaft, dass wir zweifeln und nicht glauben sollten, alles zu wissen, aber irgendwie klappt das bei vielen von uns nicht so gut.<\/p>\n\n\n\n<p>Also los:<br>Die erste Situation war am Ende eines Vortrags, als jemand Literaturempfehlungen gab und ich ganz sicher war, dass eine davon unpassend war. Ich war mir ganz sicher, dass das, worum es ging, in dem angegebenen Buch nicht zu finden ist. So sicher, dass ich nach dem Vortrag hinging und nachfragte (nur unter vier Augen), ob ich das richtig verstanden h\u00e4tte. H\u00e4tte ja ein Missverst\u00e4ndnis sein k\u00f6nnen, oder ein falscher Titel, eine neue Ausgabe, was auch immer. Nein, wir meinten das gleiche Buch. Ich verabschiedete mich mit einem &#8222;Oh, da erinnere ich mich gar nicht dran, ich muss in meinem Exemplar mal nachschauen.&#8220; Und dachte &#8222;Das steht da nicht drin. 100%.&#8220; Ich lag falsch.<\/p>\n\n\n\n<p>Die zweite Situation war in einem Restaurant, wo an einem gro\u00dfen Tisch eine gro\u00dfe, sehr laute Familie sa\u00df. Mehrere Genrationen, und zum Unterhaltungsprogramm geh\u00f6rte es, eins der Kinder wie in einer Quizshow auszufragen. Europ\u00e4ische L\u00e4nder mit ihren Hauptst\u00e4dten, Bundesl\u00e4nder mit ihren Hauptst\u00e4dten. Als ich ging, startete gerade die Kopfrechenrunde. Abgesehen davon, dass ich das prinzipiell unangenehm fand und zu laut, zuckte ich ein paar Mal zusammen, weil es hie\u00df, dass die Hauptstadt der Niederlande Amsterdam sei. Zucken Sie auch zusammen und denken &#8222;Ist das nicht Den Haag?&#8220;?<\/p>\n\n\n\n<p>Egal, ob das stimmt oder nicht &#8211; es w\u00e4re \u00fcbergriffig gewesen, zu dem Tisch zu gehen und in Frage zu stellen, was das Kind sagt und was vom Vater als richtig bewertet wird. Nicht meine Familie, nicht meine Baustelle, und wenn es falsch ist, dann wird das irgendwann auffallen und jemand korrigiert es. Zuhause hab ich trotzdem gleich nachgeschaut und die Erkl\u00e4rung f\u00fcr mein Gef\u00fchl gefunden: In Den Haag ist der Regierungssitz. Deshalb hing der Name dieser Stadt bei mir im Gehirn und &#8222;Amsterdam&#8220; h\u00f6rte sich falsch an. Immerhin, es hatte sich gekl\u00e4rt und ich hatte nichts &#8222;verfalschbessert&#8220;. Angesichts dessen, wie sicher ich mir aber zwischenzeitlich war, dass Den Haag auch die Hauptstadt der Niederlande ist, kam das gleiche Gef\u00fchl bei mir auf wie vorher, bei der Literaturangabe.<\/p>\n\n\n\n<p>Wie oft passiert es wohl, dass ich Quatsch denke oder erz\u00e4hle, obwohl ich mir 100% sicher bin, dass alles stimmt? Und das, obwohl ich mich im Zuge meines &#8222;Klugsch\u2026&#8220;-Managements schon zur\u00fcckhalte und oft vorsichtig formuliere. Insofern nehme ich diese beiden Erlebnisse als Lektionen. Es geht um Demut, gesunde Selbstzweifel, das Respektieren von Grenzen auch dann, wenn andere Menschen sich (tats\u00e4chlich oder vermeintlich) irren, und darum, noch mal innezuhalten besonders dann, wenn ich mir ganz, ganz sicher bin, dass ich recht habe. Dass man &#8222;recht haben&#8220; so schreibt, muss ich \u00fcbrigens auch immer mal wieder nachgucken. Mein Ego hat durch die Rechtschreibreform und nachfolgende Regelungen ganz sch\u00f6n gelitten. Aber das ist ein anderes Thema.<\/p>\n\n\n\n<p>Wann haben Sie sich zuletzt geirrt und es gemerkt, nachdem Sie vorher ganz sicher waren, recht zu haben?<br>Haben Sie manchmal den Impuls, andere Leute zu korrigieren, auch wenn das gerade nicht zu Ihrer Rolle oder Aufgabe geh\u00f6rt?<br>Wann folgen Sie dem, wann nicht?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Warnhinweis:Das ist ein Text f\u00fcr Besserwisser*innen, Rechthaber*innen und Klugschei\u2026 Sie wissen schon. Geh\u00f6ren Sie zu einer dieser Kategorien?Grunds\u00e4tzlich? Manchmal?Oder fr\u00fcher mal, und jetzt nicht mehr so? Ich muss leider zugeben, dass ich ganz sch\u00f6n rechthaberisch und besserwisserisch bin. Liegt bei mir total in der Familie. Und das hat mich wahrscheinlich gerettet, denn ich sehe dieses [&hellip;]<\/p>\n","protected":false},"author":4215,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/posts\/591"}],"collection":[{"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/users\/4215"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/comments?post=591"}],"version-history":[{"count":3,"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/posts\/591\/revisions"}],"predecessor-version":[{"id":594,"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/posts\/591\/revisions\/594"}],"wp:attachment":[{"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/media?parent=591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/categories?post=591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.urz.uni-halle.de\/waldecker\/wp-json\/wp\/v2\/tags?post=591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}